{"id":18063,"date":"2024-10-18T04:41:55","date_gmt":"2024-10-18T02:41:55","guid":{"rendered":"https:\/\/pandita.mx\/?post_type=product&#038;p=18063"},"modified":"2024-10-18T04:42:44","modified_gmt":"2024-10-18T02:42:44","slug":"tomy-daly","status":"publish","type":"product","link":"https:\/\/pandita.mx\/index.php\/producto\/tomy-daly\/","title":{"rendered":"Tomy Daly"},"content":{"rendered":"<p>Desata tu lado oscuro con nuestras playeras de villanos en Pandita.mx. Con dise\u00f1os que capturan la maldad y el carisma de los personajes m\u00e1s ic\u00f3nicos, estas prendas son perfectas para quienes prefieren a los verdaderos protagonistas del caos. \u00a1Vive el poder de los villanos con estilo y actitud!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desata tu lado oscuro con nuestras playeras de villanos en Pandita.mx. Con dise\u00f1os que capturan la maldad y el carisma de los personajes m\u00e1s ic\u00f3nicos, estas prendas son perfectas para quienes prefieren a los verdaderos protagonistas del caos. \u00a1Vive el poder de los villanos con estilo y actitud!<\/p>\n","protected":false},"featured_media":17579,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[127],"product_tag":[],"class_list":{"0":"post-18063","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-11_14-looney-tunes","7":"pa_color-blanco","8":"pa_color-negro","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/product\/18063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/comments?post=18063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/media\/17579"}],"wp:attachment":[{"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/media?parent=18063"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/product_cat?post=18063"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/product_tag?post=18063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}