{"id":16023,"date":"2024-10-15T01:57:12","date_gmt":"2024-10-14T23:57:12","guid":{"rendered":"https:\/\/pandita.mx\/?post_type=product&#038;p=16023"},"modified":"2024-10-15T02:39:00","modified_gmt":"2024-10-15T00:39:00","slug":"oso-dracula","status":"publish","type":"product","link":"https:\/\/pandita.mx\/index.php\/producto\/oso-dracula\/","title":{"rendered":"Oso Dracula"},"content":{"rendered":"<p>Luce con estilo y ternura este Halloween con nuestras playeras del Oso Fashion en Pandita.mx. Con un toque moderno y divertido, este dise\u00f1o captura la esencia de la moda y el encanto en un solo look. Perfectas para quienes quieren destacar con originalidad y elegancia. \u00a1Haz que tu outfit sea el m\u00e1s cool de la temporada!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luce con estilo y ternura este Halloween con nuestras playeras del Oso Fashion en Pandita.mx. Con un toque moderno y divertido, este dise\u00f1o captura la esencia de la moda y el encanto en un solo look. Perfectas para quienes quieren destacar con originalidad y elegancia. \u00a1Haz que tu outfit sea el m\u00e1s cool de la [&hellip;]<\/p>\n","protected":false},"featured_media":15533,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[130],"product_tag":[],"class_list":{"0":"post-16023","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-11_17-osos","7":"pa_color-blanco","8":"pa_color-negro","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/product\/16023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/comments?post=16023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/media\/15533"}],"wp:attachment":[{"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/media?parent=16023"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/product_cat?post=16023"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pandita.mx\/index.php\/wp-json\/wp\/v2\/product_tag?post=16023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}